{"id":922,"date":"2024-02-06T08:53:07","date_gmt":"2024-02-06T07:53:07","guid":{"rendered":"https:\/\/www.lerobinetdor.com\/new\/chambre-superieure\/"},"modified":"2024-03-26T18:35:34","modified_gmt":"2024-03-26T17:35:34","slug":"superior-room","status":"publish","type":"page","link":"https:\/\/www.lerobinetdor.com\/en\/superior-room\/","title":{"rendered":"Chambre sup\u00e9rieure"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"922\" class=\"elementor elementor-922\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-525856e elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"525856e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e17c34f\" data-id=\"e17c34f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-143baf4 elementor-widget elementor-widget-text-editor\" data-id=\"143baf4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<h1 style=\"text-align: center;\">SUPERIOR ROOM<\/h1>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eed7b9 elementor-widget elementor-widget-image\" data-id=\"3eed7b9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.lerobinetdor.com\/new\/wp-content\/uploads\/2020\/08\/border.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6138fd elementor-widget elementor-widget-text-editor\" data-id=\"c6138fd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2 style=\"font-size: 24px; text-align: center; text-transform: none;\">1 to 4 people<\/h2>\nThe <strong>Superior Room<\/strong> can accommodate 1 to 4 people and has a double bed or 2 single beds, as well as a convertible sofa.\nThe bathroom is equipped with a bathtub, separate toilet and L\u2019Occitane toiletries.\nFacilities: Lounge area\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b59f320 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b59f320\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.secure-hotel-booking.com\/Le-Robinet-d-Or\/2YM1\/dateselection?language=EN\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-calendar-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V192H0v272zm320-196c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zM192 268c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zM64 268c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12H76c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12H76c-6.6 0-12-5.4-12-12v-40zM400 64h-48V16c0-8.8-7.2-16-16-16h-32c-8.8 0-16 7.2-16 16v48H160V16c0-8.8-7.2-16-16-16h-32c-8.8 0-16 7.2-16 16v48H48C21.5 64 0 85.5 0 112v48h448v-48c0-26.5-21.5-48-48-48z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">BOOK<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-3aec2b6 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"3aec2b6\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e7f9bf elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"8e7f9bf\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized):not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.lerobinetdor.com\/wp-content\/uploads\/2024\/02\/superieure-ROBINET-DOR-305_1-1024x683.jpg\" alt=\"Chambre Sup\u00e9rieure Le Robinet d&#039;Or Paris\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.lerobinetdor.com\/wp-content\/uploads\/2024\/02\/superieure-ROBINET-DOR-305_9-1024x683.jpg\" alt=\"Chambre Sup\u00e9rieure Le Robinet d&#039;Or Paris\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.lerobinetdor.com\/wp-content\/uploads\/2024\/02\/superieure-ROBINET-DOR-305_2-1024x683.jpg\" alt=\"Chambre Sup\u00e9rieure Le Robinet d&#039;Or Paris\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.lerobinetdor.com\/wp-content\/uploads\/2024\/02\/superieure-ROBINET-DOR-305_3-1024x683.jpg\" alt=\"Chambre Sup\u00e9rieure Le Robinet d&#039;Or Paris\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.lerobinetdor.com\/wp-content\/uploads\/2024\/02\/superieure-ROBINET-DOR-305_4-1024x683.jpg\" alt=\"Chambre Sup\u00e9rieure Le Robinet d&#039;Or Paris\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.lerobinetdor.com\/wp-content\/uploads\/2024\/02\/superieure-ROBINET-DOR-305_5-1024x683.jpg\" alt=\"Chambre Sup\u00e9rieure Le Robinet d&#039;Or Paris\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.lerobinetdor.com\/wp-content\/uploads\/2024\/02\/superieure-ROBINET-DOR-305_6-1024x683.jpg\" alt=\"Chambre Sup\u00e9rieure Le Robinet d&#039;Or Paris\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.lerobinetdor.com\/wp-content\/uploads\/2024\/02\/superieure-ROBINET-DOR-305_7-1024x683.jpg\" alt=\"Chambre Sup\u00e9rieure Le Robinet d&#039;Or Paris\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.lerobinetdor.com\/wp-content\/uploads\/2024\/02\/superieure-ROBINET-DOR-305_8-1024x683.jpg\" alt=\"Chambre Sup\u00e9rieure Le Robinet d&#039;Or Paris\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b32a689 e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"b32a689\" data-element_type=\"container\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab46eff elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ab46eff\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.lerobinetdor.com\/en\/rooms-robinet-or-paris\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">See our other rooms<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>SUPERIOR ROOM 1 to 4 people The Superior Room can accommodate 1 to 4 people and has a double bed or 2 single beds, as well as a convertible sofa. The bathroom is equipped with a bathtub, separate toilet and L\u2019Occitane toiletries. Facilities: Lounge area&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-922","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Superior room at the Hotel Restaurant Robinet d\u2019Or Paris<\/title>\n<meta name=\"description\" content=\"The Superior Rooms of the Hotel Robinet d&#039;Or Paris, comfortable, free WiFi, quiet, double glazing private bathrooms, TV.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lerobinetdor.com\/en\/superior-room\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Superior room at the Hotel Restaurant Robinet d\u2019Or Paris\" \/>\n<meta property=\"og:description\" content=\"The Superior Rooms of the Hotel Robinet d&#039;Or Paris, comfortable, free WiFi, quiet, double glazing private bathrooms, TV.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lerobinetdor.com\/en\/superior-room\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Robinet d&#039;Or\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-26T17:35:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lerobinetdor.com\/new\/wp-content\/uploads\/2020\/08\/border.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lerobinetdor.com\/en\/superior-room\/\",\"url\":\"https:\/\/www.lerobinetdor.com\/en\/superior-room\/\",\"name\":\"Superior room at the Hotel Restaurant Robinet d\u2019Or Paris\",\"isPartOf\":{\"@id\":\"https:\/\/www.lerobinetdor.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lerobinetdor.com\/en\/superior-room\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lerobinetdor.com\/en\/superior-room\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lerobinetdor.com\/new\/wp-content\/uploads\/2020\/08\/border.png\",\"datePublished\":\"2024-02-06T07:53:07+00:00\",\"dateModified\":\"2024-03-26T17:35:34+00:00\",\"description\":\"The Superior Rooms of the Hotel Robinet d'Or Paris, comfortable, free WiFi, quiet, double glazing private bathrooms, TV.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lerobinetdor.com\/en\/superior-room\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lerobinetdor.com\/en\/superior-room\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.lerobinetdor.com\/en\/superior-room\/#primaryimage\",\"url\":\"https:\/\/www.lerobinetdor.com\/wp-content\/uploads\/2020\/08\/border.png\",\"contentUrl\":\"https:\/\/www.lerobinetdor.com\/wp-content\/uploads\/2020\/08\/border.png\",\"width\":70,\"height\":2,\"caption\":\"m\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lerobinetdor.com\/en\/superior-room\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lerobinetdor.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chambre sup\u00e9rieure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lerobinetdor.com\/#website\",\"url\":\"https:\/\/www.lerobinetdor.com\/\",\"name\":\"Le Robinet d&#039;Or\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lerobinetdor.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Superior room at the Hotel Restaurant Robinet d\u2019Or Paris","description":"The Superior Rooms of the Hotel Robinet d'Or Paris, comfortable, free WiFi, quiet, double glazing private bathrooms, TV.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lerobinetdor.com\/en\/superior-room\/","og_locale":"en_US","og_type":"article","og_title":"Superior room at the Hotel Restaurant Robinet d\u2019Or Paris","og_description":"The Superior Rooms of the Hotel Robinet d'Or Paris, comfortable, free WiFi, quiet, double glazing private bathrooms, TV.","og_url":"https:\/\/www.lerobinetdor.com\/en\/superior-room\/","og_site_name":"Le Robinet d&#039;Or","article_modified_time":"2024-03-26T17:35:34+00:00","og_image":[{"url":"https:\/\/www.lerobinetdor.com\/new\/wp-content\/uploads\/2020\/08\/border.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lerobinetdor.com\/en\/superior-room\/","url":"https:\/\/www.lerobinetdor.com\/en\/superior-room\/","name":"Superior room at the Hotel Restaurant Robinet d\u2019Or Paris","isPartOf":{"@id":"https:\/\/www.lerobinetdor.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lerobinetdor.com\/en\/superior-room\/#primaryimage"},"image":{"@id":"https:\/\/www.lerobinetdor.com\/en\/superior-room\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lerobinetdor.com\/new\/wp-content\/uploads\/2020\/08\/border.png","datePublished":"2024-02-06T07:53:07+00:00","dateModified":"2024-03-26T17:35:34+00:00","description":"The Superior Rooms of the Hotel Robinet d'Or Paris, comfortable, free WiFi, quiet, double glazing private bathrooms, TV.","breadcrumb":{"@id":"https:\/\/www.lerobinetdor.com\/en\/superior-room\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lerobinetdor.com\/en\/superior-room\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lerobinetdor.com\/en\/superior-room\/#primaryimage","url":"https:\/\/www.lerobinetdor.com\/wp-content\/uploads\/2020\/08\/border.png","contentUrl":"https:\/\/www.lerobinetdor.com\/wp-content\/uploads\/2020\/08\/border.png","width":70,"height":2,"caption":"m"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lerobinetdor.com\/en\/superior-room\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lerobinetdor.com\/en\/"},{"@type":"ListItem","position":2,"name":"Chambre sup\u00e9rieure"}]},{"@type":"WebSite","@id":"https:\/\/www.lerobinetdor.com\/#website","url":"https:\/\/www.lerobinetdor.com\/","name":"Le Robinet d&#039;Or","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lerobinetdor.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.lerobinetdor.com\/en\/wp-json\/wp\/v2\/pages\/922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lerobinetdor.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lerobinetdor.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lerobinetdor.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lerobinetdor.com\/en\/wp-json\/wp\/v2\/comments?post=922"}],"version-history":[{"count":13,"href":"https:\/\/www.lerobinetdor.com\/en\/wp-json\/wp\/v2\/pages\/922\/revisions"}],"predecessor-version":[{"id":1903,"href":"https:\/\/www.lerobinetdor.com\/en\/wp-json\/wp\/v2\/pages\/922\/revisions\/1903"}],"wp:attachment":[{"href":"https:\/\/www.lerobinetdor.com\/en\/wp-json\/wp\/v2\/media?parent=922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}